{"id":17186,"date":"2024-09-04T12:46:22","date_gmt":"2024-09-04T10:46:22","guid":{"rendered":"https:\/\/www.orreke.ee\/tootuba\/siidisall\/"},"modified":"2025-09-01T19:34:15","modified_gmt":"2025-09-01T17:34:15","slug":"silk-scarf","status":"publish","type":"tootuba","link":"https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/","title":{"rendered":"Paint a beautiful silk scarf"},"content":{"rendered":"<p>Legend has it that Chinese Empress Xi-Ling-Shi discovered silk by chance when a silkworm cocoon fell into her teacup. It was the beginning of an art that has graced the world for thousands of years. In the workshop, we will also talk about silk road and how silk once came to Europe. Why silk is such a prized textile, how many metres or kilometres of silk yarn it takes to produce a single scarf &#8211; you&#8217;ll learn all this and more in our workshop.<\/p>\n<p>In the Orrrekes workshop, you can take part in the creative magic of the ancient art of silk painting. We&#8217;ll learn the basics of silk dyes and fabric painting, and open up our creativity to paint a unique silk scarf. We use simple techniques suitable for children, adults and beginners.<\/p>\n<p>By the end of the workshop, you will have a light and elegant silk scarf &#8211; a unique souvenir from Tallinn that you can put around your neck or in a lovely gift box.<\/p>\n<p>You are welcome to paint in our studio in the Old Town of Tallinn, or we can come to you with a workshop.<\/p>\n<p>Silk painting always works, even for those who are new to it. The scarf painting workshop lasts 90 minutes and is suitable for older children (from the age of 10) and adults.<\/p>\n","protected":false},"featured_media":18821,"template":"","meta":{"_acf_changed":false},"categories":[350],"class_list":["post-17186","tootuba","type-tootuba","status-publish","has-post-thumbnail","hentry","category-textile"],"acf":{"photo_gallery":{"pildigalerii":[[{"id":18824,"title":"siidimaal, naised (2)","caption":"","full_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2.jpg","thumbnail_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-150x150.jpg","large_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-1024x683.jpg 1024w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-300x200.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-768x512.jpg 768w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-1536x1024.jpg 1536w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-1000x667.jpg 1000w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2.jpg 1800w","medium_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-300x200.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-1024x683.jpg 1024w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-768x512.jpg 768w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-1536x1024.jpg 1536w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-1000x667.jpg 1000w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2.jpg 1800w","media_details":{"width":1800,"height":1200,"sizes":{"medium":{"file":"siidimaal-naised-2-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":32795,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-300x200.jpg"},"large":{"file":"siidimaal-naised-2-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":170809,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-1024x683.jpg"},"thumbnail":{"file":"siidimaal-naised-2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":20956,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-150x150.jpg"},"medium_large":{"file":"siidimaal-naised-2-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":110535,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-768x512.jpg"},"1536x1536":{"file":"siidimaal-naised-2-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":319629,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-1536x1024.jpg"},"woocommerce_thumbnail":{"file":"siidimaal-naised-2-400x400.jpg","width":400,"height":400,"mime-type":"image\/jpeg","filesize":58418,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-400x400.jpg"},"woocommerce_single":{"file":"siidimaal-naised-2-1000x667.jpg","width":1000,"height":667,"mime-type":"image\/jpeg","filesize":164608,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-1000x667.jpg"},"woocommerce_gallery_thumbnail":{"file":"siidimaal-naised-2-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":16546,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-2-100x100.jpg"}}},"alt_text":"","url":"","target":""},{"id":18821,"title":"siidimaal naised (3)","caption":"","full_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3.jpg","thumbnail_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-150x150.jpg","large_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-1024x683.jpg 1024w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-300x200.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-768x512.jpg 768w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-1536x1024.jpg 1536w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-1000x667.jpg 1000w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3.jpg 1800w","medium_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-300x200.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-1024x683.jpg 1024w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-768x512.jpg 768w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-1536x1024.jpg 1536w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-1000x667.jpg 1000w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3.jpg 1800w","media_details":{"width":1800,"height":1200,"sizes":{"medium":{"file":"siidimaal-naised-3-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":30974,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-300x200.jpg"},"large":{"file":"siidimaal-naised-3-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":147022,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-1024x683.jpg"},"thumbnail":{"file":"siidimaal-naised-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":20900,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-150x150.jpg"},"medium_large":{"file":"siidimaal-naised-3-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":97474,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-768x512.jpg"},"1536x1536":{"file":"siidimaal-naised-3-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":264074,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-1536x1024.jpg"},"woocommerce_thumbnail":{"file":"siidimaal-naised-3-400x400.jpg","width":400,"height":400,"mime-type":"image\/jpeg","filesize":55579,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-400x400.jpg"},"woocommerce_single":{"file":"siidimaal-naised-3-1000x667.jpg","width":1000,"height":667,"mime-type":"image\/jpeg","filesize":141962,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-1000x667.jpg"},"woocommerce_gallery_thumbnail":{"file":"siidimaal-naised-3-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":16617,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3-100x100.jpg"}}},"alt_text":"","url":"","target":""},{"id":18818,"title":"siidimaal naised (1)","caption":"","full_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1.jpg","thumbnail_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-150x150.jpg","large_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-1024x683.jpg 1024w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-300x200.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-768x512.jpg 768w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-1536x1024.jpg 1536w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-1000x667.jpg 1000w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1.jpg 1800w","medium_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-300x200.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-1024x683.jpg 1024w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-768x512.jpg 768w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-1536x1024.jpg 1536w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-1000x667.jpg 1000w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1.jpg 1800w","media_details":{"width":1800,"height":1200,"sizes":{"medium":{"file":"siidimaal-naised-1-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":30832,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-300x200.jpg"},"large":{"file":"siidimaal-naised-1-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":157060,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-1024x683.jpg"},"thumbnail":{"file":"siidimaal-naised-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":19897,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-150x150.jpg"},"medium_large":{"file":"siidimaal-naised-1-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":102129,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-768x512.jpg"},"1536x1536":{"file":"siidimaal-naised-1-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":290508,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-1536x1024.jpg"},"woocommerce_thumbnail":{"file":"siidimaal-naised-1-400x400.jpg","width":400,"height":400,"mime-type":"image\/jpeg","filesize":53186,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-400x400.jpg"},"woocommerce_single":{"file":"siidimaal-naised-1-1000x667.jpg","width":1000,"height":667,"mime-type":"image\/jpeg","filesize":150960,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-1000x667.jpg"},"woocommerce_gallery_thumbnail":{"file":"siidimaal-naised-1-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":16020,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-1-100x100.jpg"}}},"alt_text":"","url":"","target":""},{"id":16683,"title":"siidimaal (2)","caption":"","full_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2.jpg","thumbnail_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2-150x150.jpg","large_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2.jpg 831w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2-300x217.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2-768x555.jpg 768w","medium_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2-300x217.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2-768x555.jpg 768w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2.jpg 831w","media_details":{"width":831,"height":600,"sizes":{"woocommerce_thumbnail":{"file":"siidimaal-2-400x400.jpg","width":400,"height":400,"mime-type":"image\/jpeg","filesize":42392,"uncropped":false,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2-400x400.jpg"},"woocommerce_gallery_thumbnail":{"file":"siidimaal-2-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":4577,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2-100x100.jpg"},"woocommerce_single":{"file":"siidimaal-2-300x217.jpg","width":300,"height":217,"mime-type":"image\/jpeg","filesize":20150,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2.jpg"},"medium":{"file":"siidimaal-2-300x217.jpg","width":300,"height":217,"mime-type":"image\/jpeg","filesize":20150,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2-300x217.jpg"},"thumbnail":{"file":"siidimaal-2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8574,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2-150x150.jpg"},"medium_large":{"file":"siidimaal-2-768x555.jpg","width":768,"height":555,"mime-type":"image\/jpeg","filesize":96733,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/siidimaal-2-768x555.jpg"}}},"alt_text":"","url":"","target":""},{"id":16538,"title":"20190617_115716","caption":"","full_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489.jpg","thumbnail_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-150x150.jpg","large_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-1024x576.jpg 1024w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-1000x562.jpg 1000w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-300x169.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-768x432.jpg 768w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489.jpg 1067w","medium_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-300x169.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-1000x562.jpg 1000w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-1024x576.jpg 1024w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-768x432.jpg 768w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489.jpg 1067w","media_details":{"width":1067,"height":600,"sizes":{"woocommerce_thumbnail":{"file":"20190617_115716-e1567102275489-400x400.jpg","width":400,"height":400,"mime-type":"image\/jpeg","filesize":25471,"uncropped":false,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-400x400.jpg"},"woocommerce_gallery_thumbnail":{"file":"20190617_115716-e1567102275489-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":2941,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-100x100.jpg"},"woocommerce_single":{"file":"20190617_115716-e1567102275489-1000x562.jpg","width":1000,"height":562,"mime-type":"image\/jpeg","filesize":72513,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-1000x562.jpg"},"medium":{"file":"20190617_115716-e1567102275489-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":10558,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-300x169.jpg"},"large":{"file":"20190617_115716-e1567102275489-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":74582,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-1024x576.jpg"},"thumbnail":{"file":"20190617_115716-e1567102275489-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5417,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-150x150.jpg"},"medium_large":{"file":"20190617_115716-e1567102275489-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":47940,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/20190617_115716-e1567102275489-768x432.jpg"}}},"alt_text":"","url":"","target":""},{"id":16215,"title":"","caption":"","full_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4.jpg","thumbnail_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4-150x150.jpg","large_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4.jpg 831w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4-300x217.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4-768x555.jpg 768w","medium_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4-300x217.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4-768x555.jpg 768w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4.jpg 831w","media_details":{"width":831,"height":600,"sizes":{"woocommerce_thumbnail":{"file":"1607-4-400x400.jpg","width":400,"height":400,"mime-type":"image\/jpeg","filesize":41716,"uncropped":false,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4-400x400.jpg"},"woocommerce_gallery_thumbnail":{"file":"1607-4-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":4717,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4-100x100.jpg"},"woocommerce_single":{"file":"1607-4-300x217.jpg","width":300,"height":217,"mime-type":"image\/jpeg","filesize":20948,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4.jpg"},"medium":{"file":"1607-4-300x217.jpg","width":300,"height":217,"mime-type":"image\/jpeg","filesize":20948,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4-300x217.jpg"},"thumbnail":{"file":"1607-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8722,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4-150x150.jpg"},"medium_large":{"file":"1607-4-768x555.jpg","width":768,"height":555,"mime-type":"image\/jpeg","filesize":100216,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/1607-4-768x555.jpg"}}},"alt_text":"","url":"","target":""},{"id":16161,"title":"","caption":"\u00d6rrekese meistrikoda tuleb kohale Sinu t\u00e4htp\u00e4evale olgu selleks s\u00fcnnip\u00e4ev v\u00f5i perep\u00e4ev, suur firmapidu v\u00f5i t\u00fcdrukute\u00f5htu. \u00d5pitubades meisterdame kingitusi nii iseendale kui teistele.","full_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E.jpg","thumbnail_image_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E-150x150.jpg","large_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E.jpg 800w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E-300x213.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E-768x545.jpg 768w","medium_srcset":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E-300x213.jpg 300w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E-768x545.jpg 768w, https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E.jpg 800w","media_details":{"width":800,"height":568,"sizes":{"woocommerce_thumbnail":{"file":"Pg1411-9222-E-400x400.jpg","width":400,"height":400,"mime-type":"image\/jpeg","filesize":41990,"uncropped":false,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E-400x400.jpg"},"woocommerce_gallery_thumbnail":{"file":"Pg1411-9222-E-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":4797,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E-100x100.jpg"},"woocommerce_single":{"file":"Pg1411-9222-E-300x213.jpg","width":300,"height":213,"mime-type":"image\/jpeg","filesize":21006,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E.jpg"},"medium":{"file":"Pg1411-9222-E-300x213.jpg","width":300,"height":213,"mime-type":"image\/jpeg","filesize":21006,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E-300x213.jpg"},"thumbnail":{"file":"Pg1411-9222-E-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8887,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E-150x150.jpg"},"medium_large":{"file":"Pg1411-9222-E-768x545.jpg","width":768,"height":545,"mime-type":"image\/jpeg","filesize":94552,"source_url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2016\/06\/Pg1411-9222-E-768x545.jpg"}}},"alt_text":"","url":"","target":""}]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paint a beautiful silk scarf - \u00d6rreke<\/title>\n<meta name=\"description\" content=\"- In the workshop, you will make a beautiful and unique scarf using silk painting techniques. It&#039;s a technique that always works, even for beginners.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paint a beautiful silk scarf - \u00d6rreke\" \/>\n<meta property=\"og:description\" content=\"- In the workshop, you will make a beautiful and unique scarf using silk painting techniques. It&#039;s a technique that always works, even for beginners.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00d6rreke\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/orreke\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-01T17:34:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/workshop\\\/silk-scarf\\\/\",\"url\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/workshop\\\/silk-scarf\\\/\",\"name\":\"Paint a beautiful silk scarf - \u00d6rreke\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/workshop\\\/silk-scarf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/workshop\\\/silk-scarf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.orreke.ee\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/siidimaal-naised-3.jpg\",\"datePublished\":\"2024-09-04T10:46:22+00:00\",\"dateModified\":\"2025-09-01T17:34:15+00:00\",\"description\":\"- In the workshop, you will make a beautiful and unique scarf using silk painting techniques. It's a technique that always works, even for beginners.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/workshop\\\/silk-scarf\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.orreke.ee\\\/en\\\/workshop\\\/silk-scarf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/workshop\\\/silk-scarf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.orreke.ee\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/siidimaal-naised-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.orreke.ee\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/siidimaal-naised-3.jpg\",\"width\":1800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/workshop\\\/silk-scarf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paint a beautiful silk scarf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/\",\"name\":\"\u00d6rreke\",\"description\":\"Rohkem kui pelgalt k\u00e4sit\u00f6\u00f6!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/#organization\"},\"alternateName\":\"K\u00e4sit\u00f6\u00f6 \u00f5pitoad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/#organization\",\"name\":\"\u00d6rreke\",\"alternateName\":\"K\u00e4sit\u00f6\u00f6 \u00f5pitoad Sinu \u00fcritusel\",\"url\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.orreke.ee\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/ORREKE.svg\",\"contentUrl\":\"https:\\\/\\\/www.orreke.ee\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/ORREKE.svg\",\"caption\":\"\u00d6rreke\"},\"image\":{\"@id\":\"https:\\\/\\\/www.orreke.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/orreke\\\/\",\"https:\\\/\\\/www.instagram.com\\\/orrekesemeistrikoda\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/orrekese-meistrikoda\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paint a beautiful silk scarf - \u00d6rreke","description":"- In the workshop, you will make a beautiful and unique scarf using silk painting techniques. It's a technique that always works, even for beginners.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/","og_locale":"en_US","og_type":"article","og_title":"Paint a beautiful silk scarf - \u00d6rreke","og_description":"- In the workshop, you will make a beautiful and unique scarf using silk painting techniques. It's a technique that always works, even for beginners.","og_url":"https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/","og_site_name":"\u00d6rreke","article_publisher":"https:\/\/www.facebook.com\/orreke\/","article_modified_time":"2025-09-01T17:34:15+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/","url":"https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/","name":"Paint a beautiful silk scarf - \u00d6rreke","isPartOf":{"@id":"https:\/\/www.orreke.ee\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/#primaryimage"},"image":{"@id":"https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3.jpg","datePublished":"2024-09-04T10:46:22+00:00","dateModified":"2025-09-01T17:34:15+00:00","description":"- In the workshop, you will make a beautiful and unique scarf using silk painting techniques. It's a technique that always works, even for beginners.","breadcrumb":{"@id":"https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/#primaryimage","url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3.jpg","contentUrl":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/09\/siidimaal-naised-3.jpg","width":1800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.orreke.ee\/en\/workshop\/silk-scarf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.orreke.ee\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"Paint a beautiful silk scarf"}]},{"@type":"WebSite","@id":"https:\/\/www.orreke.ee\/en\/#website","url":"https:\/\/www.orreke.ee\/en\/","name":"\u00d6rreke","description":"Rohkem kui pelgalt k\u00e4sit\u00f6\u00f6!","publisher":{"@id":"https:\/\/www.orreke.ee\/en\/#organization"},"alternateName":"K\u00e4sit\u00f6\u00f6 \u00f5pitoad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.orreke.ee\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.orreke.ee\/en\/#organization","name":"\u00d6rreke","alternateName":"K\u00e4sit\u00f6\u00f6 \u00f5pitoad Sinu \u00fcritusel","url":"https:\/\/www.orreke.ee\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.orreke.ee\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/08\/ORREKE.svg","contentUrl":"https:\/\/www.orreke.ee\/wp-content\/uploads\/2024\/08\/ORREKE.svg","caption":"\u00d6rreke"},"image":{"@id":"https:\/\/www.orreke.ee\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/orreke\/","https:\/\/www.instagram.com\/orrekesemeistrikoda\/","https:\/\/www.linkedin.com\/company\/orrekese-meistrikoda\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.orreke.ee\/en\/wp-json\/wp\/v2\/tootuba\/17186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orreke.ee\/en\/wp-json\/wp\/v2\/tootuba"}],"about":[{"href":"https:\/\/www.orreke.ee\/en\/wp-json\/wp\/v2\/types\/tootuba"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orreke.ee\/en\/wp-json\/wp\/v2\/media\/18821"}],"wp:attachment":[{"href":"https:\/\/www.orreke.ee\/en\/wp-json\/wp\/v2\/media?parent=17186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orreke.ee\/en\/wp-json\/wp\/v2\/categories?post=17186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}